{"id":26742,"date":"2023-02-01T18:34:19","date_gmt":"2023-02-01T17:34:19","guid":{"rendered":"https:\/\/www.cenresig.org\/final\/?p=26742"},"modified":"2023-02-01T18:34:19","modified_gmt":"2023-02-01T17:34:19","slug":"dichiarazione-riguardante-il-culto-di-dogyal-shugden","status":"publish","type":"post","link":"https:\/\/www.cenresig.org\/final\/dichiarazione-riguardante-il-culto-di-dogyal-shugden\/","title":{"rendered":"DICHIARAZIONE RIGUARDANTE IL CULTO DI DOGYAL\/SHUGDEN"},"content":{"rendered":"<div class=\"row \"><div class=\"wpv-grid grid-1-1  wpv-first-level first unextended\" style=\"padding-top:0px;padding-bottom:0px\" id=\"wpv-column-b533eb3b011e09cea70e8ddb7ebe4ed8\" ><p>I sottoscritti Centri Buddhisti desiderano esprimere totale fiducia e rispetto verso Sua Santit\u00e0 il Dalai Lama e\u00a0completo accordo per quanto riguarda la pericolosit\u00e0 della pratica del culto di Dogyal\/Shugden.<br \/>\nDal 1978 Sua Santit\u00e0 il XIV Dalai Lama, in qualit\u00e0 di leader spirituale, ha pubblicamente evidenziato quanto\u00a0la pratica dello spirito chiamato Dogyal\/Shugden sia degenerata al punto da assumere la connotazione di un\u00a0vero e proprio culto, con forti caratteristiche settarie.<br \/>\nStoricamente, i seguaci pi\u00f9 fanatici di questo culto sono\u00a0stati protagonisti di iniziative settarie che sono spesso sfociate in azioni persecutorie e violente nei confronti\u00a0di altre scuole del buddhismo tibetano. Hanno sempre giocato un ruolo di divisione che ha indebolito l\u2019unit\u00e0\u00a0del popolo tibetano e l\u2019armonia tra i praticanti. Non \u00e8 un mistero che all\u2019interno della Cina, i seguaci di\u00a0questo culto godano del sostegno dei gruppi pi\u00f9 retrivi che si oppongono a qualsiasi dialogo con il Dalai\u00a0Lama.<br \/>\nNel passato tale spirito veniva spesso invocato sia come protettore del Dharma, sia per ragioni pi\u00f9 mondane,\u00a0ma vi sono sempre stati punti di vista molto contraddittori sulla sua natura e funzione.<br \/>\nPer questo, sebbene ne\u00a0abbia seguito la pratica fino all\u2019et\u00e0 di quarant\u2019anni, dal 1975 il Dalai Lama stesso ha deciso, dopo una lunga\u00a0serie di ricerche, non solo di interromperla, ma anche di rendere pubblici i problemi storici, sociali e culturali\u00a0che sono collegati ad essa.<\/p>\n<p>In breve, la nocivit\u00e0 di Dogyal\/Shugden pu\u00f2 essere riassunta come segue:<br \/>\n\u2022 contrariamente a quanto affermato dai suoi seguaci, Dogyal\/Shugden non \u00e8 un protettore illuminato,ma un essere che \u00e8 sorto per effetto di preghiere e invocazioni distorte;<br \/>\n\u2022 la sua natura \u00e8 quella di uno spirito nocivo demoniaco;<br \/>\n\u2022 il suo effetto \u00e8 quello di distruggere il Buddhadharma e danneggiare gli altri esseri.<\/p>\n<p>I problemi derivanti dalla sua pratica sono riassumibili in tre punti essenziali:<br \/>\n\u2022 Vi \u00e8 il pericolo che il Buddhismo Tibetano degeneri in una forma di culto degli spiriti, in quanto la\u00a0pratica di Dogyal\/Shugden porta coloro che la seguono a considerare questo spirito come pi\u00f9<br \/>\nimportante del Buddha stesso.<br \/>\n\u2022 C\u2019\u00e8 la concreta possibilit\u00e0 che tale pratica costituisca un ostacolo insormontabile verso la creazione\u00a0di un\u2019autentica cultura non settaria, in totale contrasto con uno degli obiettivi che pi\u00f9 stanno a cuore\u00a0a Sua Santit\u00e0, ovvero la promozione di una sincera armonia tra le diverse religioni.<br \/>\n\u2022 Infine, vi sono seri problemi connessi alla preservazione della cultura Tibetana, emersi gi\u00e0 ai tempi\u00a0del V Dalai Lama (XVII secolo).<\/p>\n<p>Per queste ragioni, i praticanti di Dharma appartenenti ai sottoscritti Centri si impegnano costantemente a far\u00a0conoscere la verit\u00e0 su questa annosa questione, che \u2013ripetiamo \u2013 \u00e8 supportata da un\u2019ampia\u00a0documentazione analizzata accuratamente. Mosso dalla sua grande compassione, sentendo su di s\u00e9 la\u00a0responsabilit\u00e0 che gli deriva dal ruolo di guida religiosa \u2013 ovvero di colui che deve indicare il corretto\u00a0sentiero spirituale da seguire \u2013 Sua Santit\u00e0 sconsiglia di praticare il culto di questo spirito non per suo\u00a0interesse personale, ma perch\u00e9 ne \u00e8 dimostrata la pericolosit\u00e0 per i praticanti stessi.<br \/>\nPertanto, i sottoscritti Centri si dissociano e condannano fermamente qualsiasi forma di protesta nei confronti\u00a0di Sua Santit\u00e0 il Dalai Lama, promossa da organizzazioni dedite al culto di Dogyal\/Shugden che, volendo\u00a0fomentare in modo strumentale una campagna denigratoria nei Suoi confronti diffondono accuse totalmente\u00a0prive di fondamento:<br \/>\n\u2022 Sua Santit\u00e0 viene accusato di proibire tale pratica; ci\u00f2 \u00e8 falso poich\u00e9, come ripetutamente affermato\u00a0dal Dalai Lama stesso, la scelta di non coltivare questa pratica \u00e8 individuale e deve essere fatta non\u00a0per mera accettazione delle sue parole, ma dopo un\u2019analisi accurata di ci\u00f2 che viene detto. Quanto alla richiesta di Sua Santit\u00e0 che i praticanti di Dogyal\/Shugden non partecipino ai suoi insegnamenti,\u00a0iniziazioni o conferimento di voti, in qualit\u00e0 di maestro spirituale, egli ha ogni diritto di decidere chi\u00a0pu\u00f2 prendervi parte, e lo fa per la ragione che ci\u00f2 metterebbe in pericolo sia il maestro che gli\u00a0studenti a causa di una relazione contaminata.<br \/>\n\u2022 Sua Santit\u00e0 viene accusato di sopprimere la libert\u00e0 di religione: ci\u00f2 \u00e8 falso poich\u00e9 a nessuno \u00e8 stato\u00a0mai impedito di invocare questo spirito privatamente o nei templi e monasteri dove questa pratica\u00a0venga seguita. Vi sono stati dei casi in cui i seguaci di Dogyal\/Shugden si sono allontanati dai\u00a0Monasteri di origine, ma ci\u00f2 \u00e8 avvenuto in<br \/>\nseguito a referendum eseguito in conformit\u00e0 alle regole della tradizione monastica Vinaya e sono stati liberi\u00a0di tenere le loro quote di terreni e denaro e di praticare Dogyal\/Shugden per conto proprio senza alcuna\u00a0minaccia alle loro attivit\u00e0. Inoltre, se vi \u00e8 mancanza di libert\u00e0 religiosa, come \u00e8 possibile che i propiziatori di\u00a0Dogyal\/Shugden possano viaggiare ovunque, sollevando questa questione e cercando sostenitori della\u00a0propria causa tra persone completamente all\u2019oscuro dei fatti?<br \/>\n\u2022 Si sostiene che il Dalai Lama starebbe mentendo: \u00e8 una critica priva di fondamento poich\u00e9 avere\u00a0un punto di vista diverso dai praticanti di Dogyal\/Shugden non \u00e8 mentire, ma solo esercitare il diritto\u00a0ad avere una propria opinione.<br \/>\n\u2022 Il Dalai Lama \u00e8 accusato di essere l\u2019unico a sostenere questo punto di vista; ci\u00f2 \u00e8 decisamente falso\u00a0poich\u00e9 le prime controversie risalgono gi\u00e0 al XVII secolo.<\/p>\n<p>Va segnalato inoltre che le proteste di alcuni praticanti di Shugden sono degenerate fino a sfociare in veri e\u00a0propri episodi criminali, come quello accaduto a Dharamsala nel 1997 quando due seguaci di questo culto,\u00a0attualmente ricercati dalla Interpol, hanno ucciso l\u2019allora Responsabile della scuola di Dialettica e due suoi\u00a0discepoli. Inoltre, il fatto che le organizzazioni a sostegno del culto di Shugden, si siano pi\u00f9 volte espresse a\u00a0favore delle decisioni di alcuni governi occidentali di non incontrare Sua Santit\u00e0 a causa delle forti pressioni\u00a0politiche ed economiche esercitate dal Governo Cinese (come accaduto recentemente in Norvegia) fa ritenere\u00a0che altri siano gli interessi in gioco e che nulla abbiano a che vedere con aspetti legati alla tradizione\u00a0religiosa.<\/p>\n<p>Nell\u2019invitare quindi tutti coloro che sono all\u2019oscuro di questa questione a fare molta attenzione nello\u00a0scegliere la propria via spirituale, sulla base di analisi e ricerche accurate, i sottoscritti Centri Buddhisti\u00a0ribadiscono con forza il loro totale sostegno nei confronti di Sua Santit\u00e0 il Dalai Lama e delle attivit\u00e0\u00a0che Egli sta portando avanti da oltre cinquant\u2019anni in tutto il mondo, dove la sua figura viene riconosciuta\u00a0come quella di uno dei pi\u00f9 grandi fautori della pace e della armonia mondiale dei nostri tempi.<\/p>\n<p>ISTITUTO LAMA TZONG KHAPA, Pomaia (PI)<br \/>\nGHE PEL LING ISTITUTO STUDI DI BUDDHISMO TIBETANO, Milano<br \/>\nCENTRO MILAREPA, Torino<br \/>\nCOMUNIT\u00c0 DZOG-CHEN, Arcidosso (GR)<br \/>\nFPMT FONDAZIONE PER LA PRESERVAZIONE DELLA TRADIZIONE MAHAYANA, Pomaia (PI)<br \/>\nCENTRO STUDI KALACHAKRA, Bordighera (IM)<br \/>\nCENTRO DHARMA VISHUDDHA, Verona<br \/>\nCENTRO STUDI CENRESIG, Bologna<br \/>\nCENTRO MUNI GYANA, Palermo<br \/>\nCENTRO TARA CITTAMANI, Padova<br \/>\nCENTRO STUDI DROLKAR, Genova<br \/>\nShenpen Samten Ling\u2013 MonastEro femminile, Pomaia (PI)<br \/>\nTAKDEN SHEDRUP TARGYE LING\u2013MONASTERO MASCHILE, Pomaia (PI)<br \/>\nISTITUTO SAMANTABHADRA, Roma<br \/>\nMANDALA CENTRO STUDI TIBETANI, Milano<br \/>\nCENTRO STUDI TIBETANI SANGYE CIOELING, Sondrio<br \/>\nMONASTERO MANDALA SAMTEN LING, Biella<br \/>\nCENTRO STUDI TIBETANI MANDALA DEUA LING, Merano (BZ) CENTRO TERRA DI UNIFICAZIONE EWAM, Firenze<br \/>\nCENTRO VAJRAPANI, Bosentino (TN)<br \/>\nCENTRO DHARMA KARUNA, Modena<br \/>\nCENTRO LAMA TZONG KHAPA, Zero Branco (TV)<br \/>\nCENTRO STUDI TIBETANI TENZIN CIO LING, Sondrio<br \/>\nCENTRO GAJANG GIANG CHUB, Paladina (BG)<br \/>\nCENTRO BUDDHISTA CENRESIG, Domodossola (VB)<br \/>\nCENTRO SHAKYAMUNI, Messina<br \/>\nCENTRO DI MEDITAZIONE KUSHI LING, Arco (TN)<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I sottoscritti Centri Buddhisti desiderano esprimere totale fiducia e rispetto verso Sua Santit\u00e0 il Dalai Lama e\u00a0completo accordo per quanto riguarda la pericolosit\u00e0 della pratica del culto di Dogyal\/Shugden. Dal&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153],"tags":[],"class_list":["post-26742","post","type-post","status-publish","format-standard","hentry","category-documenti"],"_links":{"self":[{"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/posts\/26742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/comments?post=26742"}],"version-history":[{"count":1,"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/posts\/26742\/revisions"}],"predecessor-version":[{"id":26743,"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/posts\/26742\/revisions\/26743"}],"wp:attachment":[{"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/media?parent=26742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/categories?post=26742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cenresig.org\/final\/wp-json\/wp\/v2\/tags?post=26742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}